{"id":25,"date":"2023-06-03T06:00:40","date_gmt":"2023-06-03T06:00:40","guid":{"rendered":"https:\/\/gypsangbm.com\/?page_id=25"},"modified":"2023-06-03T06:00:40","modified_gmt":"2023-06-03T06:00:40","slug":"mines","status":"publish","type":"page","link":"https:\/\/gypsangbm.com\/index.php\/mines\/","title":{"rendered":"Mines"},"content":{"rendered":"<div id=\"wppb-builder-container\" class=\"wppb-builder-container\">                <div  class=\"wppb-row-parent  wppb-row-1687857117213 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857117212  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687857125186'  data-addon-id='1687857125186'><div class='wppb-addon'><div class=\"wppb-image-addon\"><figure class=\"wppb-image-addon-content-wrap\"><div class=\"wppb-image-addon-content wppb-imginlineblock\"><img class=\"wppb-image-addon-img\" src=\"https:\/\/gypsangbm.com\/wp-content\/uploads\/2023\/06\/Mines.jpg\" alt=\"\"><\/div><\/figure><\/div><\/div><\/div><div class='wppb-builder-addon wppb-addon-1687857251151'  data-addon-id='1687857251151'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h2 class=\"wppb-addon-title\">Gypsum Mine\n<br><\/h2><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687857234277 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857234275  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687857402124'  data-addon-id='1687857402124'><div class='wppb-addon'><div class=\"wppb-text-block-addon\"><div class=\"wppb-text-block-content 0\"><h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"20\" data-lineheight=\"29px\">Introduction<\/h3><p>ALBADR TALAYI ASIA MANUFACTURING AND TRADING Company is located in Bander Lengeh County, Hormozgan Province, Iran. The company is 35 kilometers from the docks of Bandar Lengeh and owns more than 200 hectares of mines with over 25 million tons of gypsum. The mines are located in the Zagros Mountains, and geologically part of the Gachsaran formation.<\/p><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857234276  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687857396100'  data-addon-id='1687857396100'><div class='wppb-addon'><div class=\"wppb-image-addon\"><figure class=\"wppb-image-addon-content-wrap\"><div class=\"wppb-image-addon-content wppb-imginlineblock\"><img class=\"wppb-image-addon-img\" src=\"https:\/\/gypsangbm.com\/wp-content\/uploads\/2023\/06\/Intro-400x288-1.png\" alt=\"\"><\/div><\/figure><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687858561164 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858561162  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858596750'  data-addon-id='1687858596750'><div class='wppb-addon'><div class=\"wppb-image-addon\"><figure class=\"wppb-image-addon-content-wrap\"><div class=\"wppb-image-addon-content wppb-imginlineblock\"><img class=\"wppb-image-addon-img\" src=\"https:\/\/gypsangbm.com\/wp-content\/uploads\/2023\/06\/Target-400x288-1.png\" alt=\"\"><\/div><\/figure><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858561163  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858586971'  data-addon-id='1687858586971'><div class='wppb-addon'><div class=\"wppb-text-block-addon\"><div class=\"wppb-text-block-content 0\"><h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"20\" data-lineheight=\"29px\">Outlook<\/h3><p>After obtaining operating permissions from the Ministry of Industry, Mine and Trade and other authorities in 2015, ALBADR TALAYI ASIA MANUFACTURING AND TRADING Co. started to equip and operationalize its mine and factory complex. The complex started its operations 10 months ago and is currently producing gypsum. Some of the performed activities include site building for the factory, connecting to a 500kW electricity grid, installing crushers, purchasing machinery and industrial scale in addition to road building.<\/p><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687858644308 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858644309  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858644310'  data-addon-id='1687858644310'><div class='wppb-addon'><div class=\"wppb-text-block-addon\"><div class=\"wppb-text-block-content 0\"><h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"20\" data-lineheight=\"29px\">Equipment and Production Power<\/h3><p>Presently, the factory utilizes a crushing line with a production capacity of 160 tons of gypsum per hour. It can produce macadam in sizes ranging between 0-20, 0-40, 0-50, and 50-250 millimeters.<\/p><p>The machinery and equipment utilized by ALBADR TALAYI ASIA MANUFACTURING AND TRADING Co. are as follows:<\/p><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858644311  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858644312'  data-addon-id='1687858644312'><div class='wppb-addon'><div class=\"wppb-image-addon\"><figure class=\"wppb-image-addon-content-wrap\"><div class=\"wppb-image-addon-content wppb-imginlineblock\"><img class=\"wppb-image-addon-img\" src=\"https:\/\/gypsangbm.com\/wp-content\/uploads\/2023\/06\/Tools-400x288-1.png\" alt=\"\"><\/div><\/figure><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687857642407 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857642402  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858173109'  data-addon-id='1687858173109'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h4 class=\"wppb-addon-title\">3<br>\nExcavators<\/h4><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857642403  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858237540'  data-addon-id='1687858237540'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h4 class=\"wppb-addon-title\">4<br>\nHeavy Trucks<\/h4><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857642404  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858323514'  data-addon-id='1687858323514'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h4 class=\"wppb-addon-title\">1<br>\nLoader<\/h4><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857642405  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858346394'  data-addon-id='1687858346394'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h4 class=\"wppb-addon-title\">10<br>\n18 Wheel Trucks<\/h4><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687857642406  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858386652'  data-addon-id='1687858386652'><div class='wppb-addon'><div class=\"wppb-headline-addon\"><div class=\"wppb-headline-content\"><h4 class=\"wppb-addon-title\">1<br>\n60-tonne industrial scale<\/h4><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687858448758 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858448757  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858458448'  data-addon-id='1687858458448'><div class='wppb-addon'><div class=\"wppb-text-block-addon\"><div class=\"wppb-text-block-content 0\"><p>A 500 kW power network And Repairs yard<\/p><p>The mine and factory operate in two shifts: the morning shift starting at 8 AM and the afternoon shift (16 working hours). Thanks to this complex, 25 persons are under direct employment and 20 persons are under indirect employment.<\/p><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687858644331 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858644332  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858644333'  data-addon-id='1687858644333'><div class='wppb-addon'><div class=\"wppb-image-addon\"><figure class=\"wppb-image-addon-content-wrap\"><div class=\"wppb-image-addon-content wppb-imginlineblock\"><img class=\"wppb-image-addon-img\" src=\"https:\/\/gypsangbm.com\/wp-content\/uploads\/2023\/06\/Premium-400x288-1.png\" alt=\"\"><\/div><\/figure><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858644334  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858644335'  data-addon-id='1687858644335'><div class='wppb-addon'><div class=\"wppb-text-block-addon\"><div class=\"wppb-text-block-content 0\"><h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"20\" data-lineheight=\"29px\">Our Distinctive Features<\/h3><p>Compared to other mines, this mine has the advantage of economic, quick shipping from the nearby port to the Persian Gulf countries. The company can ship 2,000 \u2013 50,000 tons of cargo via the sea routes. The products are certified by standards and licenses issued from competent organizations.<\/p><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t                <div  class=\"wppb-row-parent  wppb-row-1687858644354 \"  >\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wppb-container \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n                        <div class=\"wppb-row\">\n\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858644355  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858644356'  data-addon-id='1687858644356'><div class='wppb-addon'><div class=\"wppb-text-block-addon\"><div class=\"wppb-text-block-content 0\"><h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"20\" data-lineheight=\"29px\">How to Contract<\/h3><p>The company guarantees to provide the shipment information required by the inspecting authorities.<\/p><p>We would be honored to have you visit our website in order to take a tour of the complex or place orders. Furthermore, the company can offer exclusive sale contracts for up to three years to a client, after which a new contract needs to be signed.<\/p><p>Dear clients can pay in cash or through L\/C from our office in Dubai, UAE<\/p><\/div><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                                    <div  class=\"wppb-column-parent wppb-column-parent-view wppb-col-1687858644357  \"  >\n                                        <div class=\"wppb-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n                                            <div class=\"wppb-builder-addons\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='wppb-builder-addon wppb-addon-1687858644358'  data-addon-id='1687858644358'><div class='wppb-addon'><div class=\"wppb-image-addon\"><figure class=\"wppb-image-addon-content-wrap\"><div class=\"wppb-image-addon-content wppb-imginlineblock\"><img class=\"wppb-image-addon-img\" src=\"https:\/\/gypsangbm.com\/wp-content\/uploads\/2023\/06\/Contract-400x288-1.png\" alt=\"\"><\/div><\/figure><\/div><\/div><\/div>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n\t\t\t\t\t\t\t\t\t                        <\/div>\n\n                    <\/div>\n                <\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gypsum Mine IntroductionALBADR TALAYI ASIA MANUFACTURING AND TRADING Company is located in Bander Lengeh County, Hormozgan Province, Iran. The company is 35 kilometers from the docks of Bandar Lengeh and&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wppb_theme_template","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"_links":{"self":[{"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/pages\/25"}],"collection":[{"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":1,"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":26,"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions\/26"}],"wp:attachment":[{"href":"https:\/\/gypsangbm.com\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}